{"id":412,"count":1,"description":"","link":"http:\/\/www.hlxz.com.cn\/index.php\/category\/paydayloanalabama-com-needham-bad-credit-no-credit-2\/","name":"paydayloanalabama.com+needham bad credit no credit check payday loans","slug":"paydayloanalabama-com-needham-bad-credit-no-credit-2","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories\/412"}],"collection":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/posts?categories=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}