{"id":349,"count":1,"description":"","link":"http:\/\/www.hlxz.com.cn\/index.php\/category\/paydayloancolorado-net-saddle-ridge-my-payday-loan-2\/","name":"paydayloancolorado.net+saddle-ridge my payday loan","slug":"paydayloancolorado-net-saddle-ridge-my-payday-loan-2","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories\/349"}],"collection":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/posts?categories=349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}