{"id":309,"count":1,"description":"","link":"http:\/\/www.hlxz.com.cn\/index.php\/category\/elitecashadvance-com-installment-loans-ga-dallas-2\/","name":"elitecashadvance.com+installment-loans-ga+dallas nearby payday loans","slug":"elitecashadvance-com-installment-loans-ga-dallas-2","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories\/309"}],"collection":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/posts?categories=309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}