{"id":271,"count":1,"description":"","link":"http:\/\/www.hlxz.com.cn\/index.php\/category\/paydayloancolorado-net-ridgway-how-much-can-you-2\/","name":"paydayloancolorado.net+ridgway how much can you get on a payday loan","slug":"paydayloancolorado-net-ridgway-how-much-can-you-2","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories\/271"}],"collection":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/posts?categories=271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}