{"id":143,"count":1,"description":"","link":"http:\/\/www.hlxz.com.cn\/index.php\/category\/paydayloansconnecticut-com-essex-village-nearby-2\/","name":"paydayloansconnecticut.com+essex-village nearby payday loans","slug":"paydayloansconnecticut-com-essex-village-nearby-2","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories\/143"}],"collection":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.hlxz.com.cn\/index.php\/wp-json\/wp\/v2\/posts?categories=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}